{"id":21,"count":35,"description":"","link":"https:\/\/coimbee.com\/nl\/category\/coimbee-toolbox\/","name":"Coimbee toolbox","slug":"coimbee-toolbox","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coimbee toolbox Archieven - Coimbee jouw verbeter toolbox<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coimbee toolbox Archieven - Coimbee jouw verbeter toolbox\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coimbee.com\/nl\/category\/coimbee-toolbox\/\" \/>\n<meta property=\"og:site_name\" content=\"Coimbee jouw verbeter toolbox\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/category\\\/coimbee-toolbox\\\/\",\"url\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/category\\\/coimbee-toolbox\\\/\",\"name\":\"Coimbee toolbox Archieven - Coimbee jouw verbeter toolbox\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/category\\\/coimbee-toolbox\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/category\\\/coimbee-toolbox\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/home-page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coimbee toolbox\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/\",\"name\":\"Coimbee jouw verbeter toolbox\",\"description\":\"Met Coimbee wordt continu verbeteren makkelijk\",\"publisher\":{\"@id\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/#organization\",\"name\":\"Coimbee\",\"alternateName\":\"Coimbee | Jouw verbeter\u00a0toolbox\",\"url\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coimbee.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-coimbee-oranje.png\",\"contentUrl\":\"https:\\\/\\\/coimbee.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-coimbee-oranje.png\",\"width\":1600,\"height\":370,\"caption\":\"Coimbee\"},\"image\":{\"@id\":\"https:\\\/\\\/coimbee.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coimbee toolbox Archieven - Coimbee jouw verbeter toolbox","robots":{"index":"noindex","follow":"follow"},"og_locale":"nl_NL","og_type":"article","og_title":"Coimbee toolbox Archieven - Coimbee jouw verbeter toolbox","og_url":"https:\/\/coimbee.com\/nl\/category\/coimbee-toolbox\/","og_site_name":"Coimbee jouw verbeter toolbox","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/coimbee.com\/nl\/category\/coimbee-toolbox\/","url":"https:\/\/coimbee.com\/nl\/category\/coimbee-toolbox\/","name":"Coimbee toolbox Archieven - Coimbee jouw verbeter toolbox","isPartOf":{"@id":"https:\/\/coimbee.com\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/coimbee.com\/nl\/category\/coimbee-toolbox\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/coimbee.com\/nl\/category\/coimbee-toolbox\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/coimbee.com\/nl\/home-page\/"},{"@type":"ListItem","position":2,"name":"Coimbee toolbox"}]},{"@type":"WebSite","@id":"https:\/\/coimbee.com\/nl\/#website","url":"https:\/\/coimbee.com\/nl\/","name":"Coimbee jouw verbeter toolbox","description":"Met Coimbee wordt continu verbeteren makkelijk","publisher":{"@id":"https:\/\/coimbee.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coimbee.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/coimbee.com\/nl\/#organization","name":"Coimbee","alternateName":"Coimbee | Jouw verbeter\u00a0toolbox","url":"https:\/\/coimbee.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/coimbee.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/coimbee.com\/wp-content\/uploads\/2020\/10\/logo-coimbee-oranje.png","contentUrl":"https:\/\/coimbee.com\/wp-content\/uploads\/2020\/10\/logo-coimbee-oranje.png","width":1600,"height":370,"caption":"Coimbee"},"image":{"@id":"https:\/\/coimbee.com\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/coimbee.com\/nl\/wp-json\/wp\/v2\/categories\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coimbee.com\/nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/coimbee.com\/nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/coimbee.com\/nl\/wp-json\/wp\/v2\/posts?categories=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}